{"id":11789,"date":"2025-06-20T11:54:40","date_gmt":"2025-06-20T15:54:40","guid":{"rendered":"https:\/\/www.rigicon.com\/glossary-term\/alcocks-canal-pudendal-canal\/"},"modified":"2025-06-20T11:54:40","modified_gmt":"2025-06-20T15:54:40","slug":"alcock-kanal-canalis-pudendalis","status":"publish","type":"glossary-term","link":"https:\/\/www.rigicon.com\/de\/glossary-term\/alcock-kanal-canalis-pudendalis\/","title":{"rendered":"Alcock-Kanal (Canalis pudendalis)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","glossary-category":[143],"glossary-product":[104,105],"class_list":["post-11789","glossary-term","type-glossary-term","status-publish","hentry","glossary-category-anatomical-structures","glossary-product-infla10-pulse-ipp-series","glossary-product-rigi10-malleable-penile-prosthesis"],"acf":{"gt-definition":"<p>Der Alcock-Kanal, auch Pudenduskanal genannt, ist ein wichtiger anatomischer Durchgang im Becken. Es entsteht durch eine Spaltung der Obturatorfaszie, der Faszie, die den medialen Teil des Musculus obturator internus bedeckt.\u00b9&\u02d2;\u00b2 Sie kleidet die Seitenwand der Fossa ischioanalis aus.\u00b2 Der Hauptzweck des Alcock-Kanals besteht darin, als Kanal f\u00fcr wichtige neurovaskul\u00e4re Strukturen zu dienen. Konkret durchqueren die Arteria pudendus interna, die Venen pudendus interna und der Nervus pudendus diesen Kanal.\u00b9&\u02d2;\u00b2 Der Nervus perinealis, ein wichtiger Zweig des Nervus pudendus, entspringt h\u00e4ufig im Alcock-Kanal selbst oder am Austritt des Nervus pudendus.\u00b9 Das Verst\u00e4ndnis der Anatomie des Alcock-Kanals ist von entscheidender Bedeutung, da er sch\u00fctzt Diese Strukturen und ihre Beeintr\u00e4chtigung k\u00f6nnen zu erheblichen klinischen Syndromen f\u00fchren.\u00b9<\/p>","gt-synonyms":"Pudendalkanal","gt-citation":"[1] Kinter KJ, Newton BW. Anatomy, Abdomen and Pelvis, Pudendal Nerve. [Aktualisiert 2023 Feb 10]. In: StatPearls [Internet]. Treasure Island (FL): StatPearls Publishing; 2025 Jan-. Verf\u00fcgbar unter: https:\/\/www.ncbi.nlm.nih.gov\/books\/NBK554736\/\n\n[2] Wikipedia contributors. Pudendal canal. Wikipedia, The Free Encyclopedia. Verf\u00fcgbar unter: https:\/\/en.wikipedia.org\/wiki\/Pudendal_canal. Accessed May 15, 2025.\n\n[3] Standring, S. (Ed.). (2016). Gray's Anatomy: The Anatomical Basis of Clinical Practice (41st ed.). Elsevier. \n\n[4] Chiarioni G, Popa SL. Anorectal pain. In: Rao SSC, Lee YY, Ghoshal UC, eds. Clinical and Basic Neurogastroenterology and Motility. Academic Press; 2020:505-515. doi:10.1016\/b978-0-12-813037-7.00036-4 ","gt-clinical-context":"<p>Der Alcock-Kanal ist vor allem aufgrund seiner Beziehung zum Nervus pudendus und den damit verbundenen Gef\u00e4\u00dfen klinisch bedeutsam.\u00b9 Eine Einklemmung des Nervus pudendus (PNE), auch bekannt als Alcock-Kanal-Syndrom, kann auftreten, wenn der Nervus pudendus in diesem Kanal komprimiert wird.\u00b2&\u02d2;&sup4; Diese Kompression kann zu einer Vielzahl schw\u00e4chender Symptome f\u00fchren, darunter chronische Beckenschmerzen, Dammschmerzen, Schmerzen beim Geschlechtsverkehr (Dyspareunie) und ver\u00e4nderte Empfindungen in den Regionen, die vom Nervus pudendus versorgt werden (Genitalien, Perineum und Analregion).\u00b9 Die Symptome k\u00f6nnen durch l\u00e4ngeres Sitzen verschlimmert werden.<\/p>\n<p>Der Nervus pudendus, der den Alcock-Kanal durchquert, ist anf\u00e4llig f\u00fcr Verletzungen aus verschiedenen Gr\u00fcnden, einschlie\u00dflich Geburt (aufgrund von Dehnung oder Kompression w\u00e4hrend der Entbindung), l\u00e4ngerem Radfahren, direktem Trauma im Beckenbereich oder chirurgischen Eingriffen in der N\u00e4he.\u00b9 Solche Verletzungen k\u00f6nnen zu Gef\u00fchlsverlust, Stuhlinkontinenz (aufgrund der Beteiligung des unteren Rektalnervenzweigs) und Harninkontinenz (aufgrund der Beteiligung versorgender \u00c4ste) f\u00fchren der \u00e4u\u00dfere Harnr\u00f6hrensphinkter) und sexuelle Dysfunktion, einschlie\u00dflich erektiler Dysfunktion bei M\u00e4nnern und ver\u00e4nderter Erregung oder Anorgasmie bei Frauen.\u00b9<\/p>\n<p>Die Diagnose von Erkrankungen im Zusammenhang mit dem Alcock-Kanal, wie z. B. PNE, erfordert h\u00e4ufig eine Kombination aus klinischer Untersuchung, Anamnese, Untersuchungen der Nervenleitung und Bildgebung (wie MRT), um andere Ursachen f\u00fcr Beckenschmerzen auszuschlie\u00dfen. Die Behandlung kann von konservativen Ma\u00dfnahmen wie Physiotherapie, \u00c4nderungen des Lebensstils (z. B. Vermeiden von schmerzverst\u00e4rkenden Aktivit\u00e4ten) und Schmerzmitteln bis hin zu invasiveren Behandlungen wie Pudendusnervenblockaden (Injektion von An\u00e4sthetika und\/oder Kortikosteroiden in die N\u00e4he des Nervs, manchmal in oder in die N\u00e4he des Kanals gef\u00fchrt) oder chirurgischer Dekompression des Nervs im Alcock-Kanal in refrakt\u00e4ren F\u00e4llen reichen.\u00b9<\/p>","gt-related-evidence":null,"gt-featured":false,"gt-ai-referenced":false,"gt-view-count":100},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Alcock-Kanal (Canalis pudendalis)<\/title>\n<meta name=\"description\" content=\"Erfahren Sie mehr \u00fcber den Alcock-Kanal (Pudendalkanal), eine wichtige Beckenstruktur. Verstehen Sie seine Anatomie, Funktion und klinische Relevanz bei PNE.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rigicon.com\/de\/glossary-term\/alcock-kanal-canalis-pudendalis\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alcock-Kanal (Canalis pudendalis): Anatomy &amp; Klinische Bedeutung\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie mehr \u00fcber den Alcock-Kanal (Pudendalkanal), eine wichtige Beckenstruktur. Verstehen Sie seine Anatomie, Funktion und klinische Relevanz bei PNE.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rigicon.com\/de\/glossary-term\/alcock-kanal-canalis-pudendalis\/\" \/>\n<meta property=\"og:site_name\" content=\"Rigicon\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rigiconurology\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rigicon.com\/wp-content\/uploads\/2025\/05\/header-d.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Alcock-Kanal (Canalis pudendalis): Anatomy &amp; Klinische Bedeutung\" \/>\n<meta name=\"twitter:description\" content=\"Erfahren Sie mehr \u00fcber den Alcock-Kanal (Pudendalkanal), eine wichtige Beckenstruktur. Verstehen Sie seine Anatomie, Funktion und klinische Relevanz bei PNE.\" \/>\n<meta name=\"twitter:site\" content=\"@rigiconurology\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/glossary-term\\\/alcock-kanal-canalis-pudendalis\\\/\",\"url\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/glossary-term\\\/alcock-kanal-canalis-pudendalis\\\/\",\"name\":\"Alcock-Kanal (Canalis pudendalis)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/#website\"},\"datePublished\":\"2025-06-20T15:54:40+00:00\",\"description\":\"Erfahren Sie mehr \u00fcber den Alcock-Kanal (Pudendalkanal), eine wichtige Beckenstruktur. Verstehen Sie seine Anatomie, Funktion und klinische Relevanz bei PNE.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/glossary-term\\\/alcock-kanal-canalis-pudendalis\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rigicon.com\\\/de\\\/glossary-term\\\/alcock-kanal-canalis-pudendalis\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/glossary-term\\\/alcock-kanal-canalis-pudendalis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossary Terms\",\"item\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/urology-glossary\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alcock-Kanal (Canalis pudendalis)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/\",\"name\":\"Rigicon\",\"description\":\"Innovative Urological Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/#organization\"},\"alternateName\":\"Innovative Urological Solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/#organization\",\"name\":\"Rigicon, Inc.\",\"alternateName\":\"Innovative Urological Solutions\",\"url\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rigicon.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Logo-Square-Kopya.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rigicon.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Logo-Square-Kopya.jpg\",\"width\":512,\"height\":512,\"caption\":\"Rigicon, Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rigiconurology\\\/\",\"https:\\\/\\\/x.com\\\/rigiconurology\",\"https:\\\/\\\/www.instagram.com\\\/rigiconurology\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@Rigicon\\\/podcasts\",\"https:\\\/\\\/www.youtube.com\\\/Rigicon\",\"https:\\\/\\\/www.threads.net\\\/@rigiconurology\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rigicon\\\/\"],\"description\":\"Rigicon is a global provider of innovative, diverse, and complete portfolio of prosthetic urology options.\",\"email\":\"operations@rigicon.com\",\"telephone\":\"+1 (888) 202-9790\",\"legalName\":\"Rigicon, Inc.\",\"vatID\":\"81-3545645\",\"taxID\":\"81-3545645\",\"duns\":\"045247683\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alcock-Kanal (Canalis pudendalis)","description":"Erfahren Sie mehr \u00fcber den Alcock-Kanal (Pudendalkanal), eine wichtige Beckenstruktur. Verstehen Sie seine Anatomie, Funktion und klinische Relevanz bei PNE.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rigicon.com\/de\/glossary-term\/alcock-kanal-canalis-pudendalis\/","og_locale":"de_DE","og_type":"article","og_title":"Alcock-Kanal (Canalis pudendalis): Anatomy & Klinische Bedeutung","og_description":"Erfahren Sie mehr \u00fcber den Alcock-Kanal (Pudendalkanal), eine wichtige Beckenstruktur. Verstehen Sie seine Anatomie, Funktion und klinische Relevanz bei PNE.","og_url":"https:\/\/www.rigicon.com\/de\/glossary-term\/alcock-kanal-canalis-pudendalis\/","og_site_name":"Rigicon","article_publisher":"https:\/\/www.facebook.com\/rigiconurology\/","og_image":[{"width":1440,"height":718,"url":"https:\/\/www.rigicon.com\/wp-content\/uploads\/2025\/05\/header-d.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_title":"Alcock-Kanal (Canalis pudendalis): Anatomy & Klinische Bedeutung","twitter_description":"Erfahren Sie mehr \u00fcber den Alcock-Kanal (Pudendalkanal), eine wichtige Beckenstruktur. Verstehen Sie seine Anatomie, Funktion und klinische Relevanz bei PNE.","twitter_site":"@rigiconurology","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rigicon.com\/de\/glossary-term\/alcock-kanal-canalis-pudendalis\/","url":"https:\/\/www.rigicon.com\/de\/glossary-term\/alcock-kanal-canalis-pudendalis\/","name":"Alcock-Kanal (Canalis pudendalis)","isPartOf":{"@id":"https:\/\/www.rigicon.com\/de\/#website"},"datePublished":"2025-06-20T15:54:40+00:00","description":"Erfahren Sie mehr \u00fcber den Alcock-Kanal (Pudendalkanal), eine wichtige Beckenstruktur. Verstehen Sie seine Anatomie, Funktion und klinische Relevanz bei PNE.","breadcrumb":{"@id":"https:\/\/www.rigicon.com\/de\/glossary-term\/alcock-kanal-canalis-pudendalis\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rigicon.com\/de\/glossary-term\/alcock-kanal-canalis-pudendalis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rigicon.com\/de\/glossary-term\/alcock-kanal-canalis-pudendalis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.rigicon.com\/de\/"},{"@type":"ListItem","position":2,"name":"Glossary Terms","item":"https:\/\/www.rigicon.com\/de\/urology-glossary\/"},{"@type":"ListItem","position":3,"name":"Alcock-Kanal (Canalis pudendalis)"}]},{"@type":"WebSite","@id":"https:\/\/www.rigicon.com\/de\/#website","url":"https:\/\/www.rigicon.com\/de\/","name":"Rigicon","description":"Innovative Urological Solutions","publisher":{"@id":"https:\/\/www.rigicon.com\/de\/#organization"},"alternateName":"Innovative Urological Solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rigicon.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.rigicon.com\/de\/#organization","name":"Rigicon, Inc.","alternateName":"Innovative Urological Solutions","url":"https:\/\/www.rigicon.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.rigicon.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.rigicon.com\/wp-content\/uploads\/2024\/07\/cropped-Logo-Square-Kopya.jpg","contentUrl":"https:\/\/www.rigicon.com\/wp-content\/uploads\/2024\/07\/cropped-Logo-Square-Kopya.jpg","width":512,"height":512,"caption":"Rigicon, Inc."},"image":{"@id":"https:\/\/www.rigicon.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rigiconurology\/","https:\/\/x.com\/rigiconurology","https:\/\/www.instagram.com\/rigiconurology\/","https:\/\/www.youtube.com\/@Rigicon\/podcasts","https:\/\/www.youtube.com\/Rigicon","https:\/\/www.threads.net\/@rigiconurology","https:\/\/www.linkedin.com\/company\/rigicon\/"],"description":"Rigicon is a global provider of innovative, diverse, and complete portfolio of prosthetic urology options.","email":"operations@rigicon.com","telephone":"+1 (888) 202-9790","legalName":"Rigicon, Inc.","vatID":"81-3545645","taxID":"81-3545645","duns":"045247683"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.rigicon.com\/de\/wp-json\/wp\/v2\/glossary-term\/11789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rigicon.com\/de\/wp-json\/wp\/v2\/glossary-term"}],"about":[{"href":"https:\/\/www.rigicon.com\/de\/wp-json\/wp\/v2\/types\/glossary-term"}],"wp:attachment":[{"href":"https:\/\/www.rigicon.com\/de\/wp-json\/wp\/v2\/media?parent=11789"}],"wp:term":[{"taxonomy":"glossary-category","embeddable":true,"href":"https:\/\/www.rigicon.com\/de\/wp-json\/wp\/v2\/glossary-category?post=11789"},{"taxonomy":"glossary-product","embeddable":true,"href":"https:\/\/www.rigicon.com\/de\/wp-json\/wp\/v2\/glossary-product?post=11789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}