{"id":11777,"date":"2025-06-12T04:09:33","date_gmt":"2025-06-12T08:09:33","guid":{"rendered":"https:\/\/www.rigicon.com\/glossary-term\/corpus-spongiosum\/"},"modified":"2025-06-12T04:09:33","modified_gmt":"2025-06-12T08:09:33","slug":"corpus-spongiosum-harnrohrenschwellkorper","status":"publish","type":"glossary-term","link":"https:\/\/www.rigicon.com\/de\/glossary-term\/corpus-spongiosum-harnrohrenschwellkorper\/","title":{"rendered":"Corpus Spongiosum (Harnr\u00f6hrenschwellk\u00f6rper)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","glossary-category":[140],"glossary-product":[104,105],"class_list":["post-11777","glossary-term","type-glossary-term","status-publish","hentry","glossary-category-urological-anatomy","glossary-product-infla10-pulse-ipp-series","glossary-product-rigi10-malleable-penile-prosthesis"],"acf":{"gt-definition":"<p class=\"ai-optimize-6\">Der Corpus spongiosum ist eine zylindrische Masse aus schwammigem, erektilem Gef\u00e4\u00dfgewebe, die sich ventral im Penis befindet und die Harnr\u00f6hre entlang ihrer L\u00e4nge von der Peniszwiebel bis zur Spitze umgibt, wo sie sich zur Eichel ausdehnt.\u00b9 Es handelt sich um eine der drei Schwellk\u00f6rper des Penis, die unterhalb der paarigen Corpora Cavernosa liegt. Die Hauptfunktionen des Corpus spongiosum bestehen darin, zur Peniserektion beizutragen, indem er sich mit Blut f\u00fcllt, die Harnr\u00f6hre zu st\u00fctzen und vor allem die Kompression und den Verschluss der Harnr\u00f6hre w\u00e4hrend der Erektion zu verhindern und dadurch ihre Durchg\u00e4ngigkeit f\u00fcr den Samendurchgang w\u00e4hrend der Ejakulation aufrechtzuerhalten.\u00b2 Seine Struktur besteht aus einem Netzwerk miteinander verbundener Gef\u00e4\u00dfr\u00e4ume (Sinusoide), die durch Trabekel aus Bindegewebe und glattem Gewebe getrennt sind Muskel.\u00b3<\/p>","gt-synonyms":"Corpus cavernosum urethrae, schwammiger K\u00f6rper des Penis, Corpus spongiosum Penis","gt-citation":"[1] Healthline Editorial Team. Corpus Spongiosum Penis Anatomy, Function & Diagram. Healthline. January 24, 2018. Accessed May 15, 2025. https:\/\/www.healthline.com\/health\/human-body-maps\/corpus-spongiosum-penis \n\n[2] Ottenhof SR, de Graaf P, Soeterik TFW, et al. Architecture of the Corpus Spongiosum: An Anatomical Study. J Urol. 2016 Sep;196(3):919-25. DOI: 10.1016\/j.juro.2016.03.136\n\n[3] Baskin LS, Erol A, Li YW, Cunha GR. Anatomy of the mouse penis and internal prepuce. J Urol. 2001 Sep;166(3):1173-8. (Note:  (http:\/\/bit.ly\/45RSMGR) )\n\n[4] Duke University School of Medicine. Microscopic Anatomy: Male Reproductive System. 2014. Accessed May 15, 2025. https:\/\/histology.oit.duke.edu\/MBS\/Videos\/Histo\/2014-Histo-MaleRepro\/MaleReproHisto_Notes_2014.pdf \n\n[5] Lue TF. Physiology of Penile Erection and Pathophysiology of Erectile Dysfunction. In: Wein AJ, Kavoussi LR, Partin AW, Peters CA, eds. Campbell-Walsh Urology. 11th ed. Elsevier; 2016:chap 29. \n\n[6] Hsieh JT, Liu SP, Hsu GL, et al. The anatomy of the human corpus spongiosum. J Androl. 2002 Mar-Apr;23(2):274-9.","gt-clinical-context":"<p class=\"ai-optimize-7\">Das Corpus spongiosum ist in mehreren urologischen Zusammenh\u00e4ngen klinisch bedeutsam. Seine Hauptaufgabe bei der Aufrechterhaltung der Durchg\u00e4ngigkeit der Harnr\u00f6hre w\u00e4hrend der Erektion ist entscheidend f\u00fcr die normale Sexualfunktion und Fruchtbarkeit (Ejakulation). \u2075 Sch\u00e4den am Corpus spongiosum, beispielsweise bei Penisfrakturen oder Traumata, k\u00f6nnen zu Harnr\u00f6hrenverletzungen, Strikturbildung oder erektiler Dysfunktion f\u00fchren. Chirurgische Eingriffe an der Harnr\u00f6hre, wie etwa die Urethroplastik bei Strikturen oder die Reparatur einer Hypospadie, erfordern oft eine sorgf\u00e4ltige Dissektion und Behandlung des Corpus spongiosum, um dessen Vaskularit\u00e4t und Unterst\u00fctzung f\u00fcr die Harnr\u00f6hre zu erhalten.\u00b2 Bei einigen rekonstruktiven Operationen k\u00f6nnen Lappen oder Transplantate verwendet werden, die den Corpus spongiosum oder das umgebende Gewebe betreffen. Beispielsweise wurde ein Corpus spongiosum-Lappen zur Behandlung komplexer Beckenerkrankungen beschrieben.\u2074 Das Verst\u00e4ndnis der detaillierten Anatomie und Gef\u00e4\u00dfversorgung des Corpus spongiosum ist f\u00fcr Chirurgen von entscheidender Bedeutung, um Komplikationen zu minimieren und die Ergebnisse bei Penis- und Harnr\u00f6hrenoperationen zu optimieren.\u00b2 Erkrankungen wie die Peyronie-Krankheit betreffen zwar haupts\u00e4chlich die Corpora Cavernosa, k\u00f6nnen sich jedoch indirekt auf den Corpus spongiosum oder seine Funktion auswirken zur Penisverkr\u00fcmmung und den damit verbundenen Erektionsschwierigkeiten. Die Gesundheit und Integrit\u00e4t des Corpus spongiosum sind auch im Zusammenhang mit der Implantation einer Penisprothese relevant, da seine Erhaltung f\u00fcr die Harnr\u00f6hrenunterst\u00fctzung und die allgemeine Penisfunktion wichtig ist.<\/p>","gt-related-evidence":null,"gt-featured":false,"gt-ai-referenced":false,"gt-view-count":86},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Corpus Spongiosum (Harnr\u00f6hrenschwellk\u00f6rper)<\/title>\n<meta name=\"description\" content=\"Erfahren Sie mehr \u00fcber das Corpus Spongiosum, das die Harnr\u00f6hre umgebende erektile Gewebe, seine Rolle bei Erektionen und seine klinische Bedeutung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rigicon.com\/de\/glossary-term\/corpus-spongiosum-harnrohrenschwellkorper\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corpus Spongiosum (Harnr\u00f6hrenschwellk\u00f6rper): Anatomy, Function, and Klinische Bedeutung\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie mehr \u00fcber das Corpus Spongiosum, ein wichtiges erektiles Gewebe im Penis, das die Harnr\u00f6hre umgibt, seine Rolle bei der Erektion und seine klinische Bedeutung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rigicon.com\/de\/glossary-term\/corpus-spongiosum-harnrohrenschwellkorper\/\" \/>\n<meta property=\"og:site_name\" content=\"Rigicon\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rigiconurology\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rigicon.com\/wp-content\/uploads\/2025\/05\/header-d.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Corpus Spongiosum (Harnr\u00f6hrenschwellk\u00f6rper): Anatomy, Function, and Klinische Bedeutung\" \/>\n<meta name=\"twitter:description\" content=\"Erfahren Sie mehr \u00fcber das Corpus Spongiosum, ein wichtiges erektiles Gewebe im Penis, das die Harnr\u00f6hre umgibt, seine Rolle bei der Erektion und seine klinische Bedeutung.\" \/>\n<meta name=\"twitter:site\" content=\"@rigiconurology\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/glossary-term\\\/corpus-spongiosum-harnrohrenschwellkorper\\\/\",\"url\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/glossary-term\\\/corpus-spongiosum-harnrohrenschwellkorper\\\/\",\"name\":\"Corpus Spongiosum (Harnr\u00f6hrenschwellk\u00f6rper)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/#website\"},\"datePublished\":\"2025-06-12T08:09:33+00:00\",\"description\":\"Erfahren Sie mehr \u00fcber das Corpus Spongiosum, das die Harnr\u00f6hre umgebende erektile Gewebe, seine Rolle bei Erektionen und seine klinische Bedeutung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/glossary-term\\\/corpus-spongiosum-harnrohrenschwellkorper\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rigicon.com\\\/de\\\/glossary-term\\\/corpus-spongiosum-harnrohrenschwellkorper\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/glossary-term\\\/corpus-spongiosum-harnrohrenschwellkorper\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossary Terms\",\"item\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/urology-glossary\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Corpus Spongiosum (Harnr\u00f6hrenschwellk\u00f6rper)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/\",\"name\":\"Rigicon\",\"description\":\"Innovative Urological Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/#organization\"},\"alternateName\":\"Innovative Urological Solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/#organization\",\"name\":\"Rigicon, Inc.\",\"alternateName\":\"Innovative Urological Solutions\",\"url\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rigicon.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Logo-Square-Kopya.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rigicon.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-Logo-Square-Kopya.jpg\",\"width\":512,\"height\":512,\"caption\":\"Rigicon, Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rigicon.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rigiconurology\\\/\",\"https:\\\/\\\/x.com\\\/rigiconurology\",\"https:\\\/\\\/www.instagram.com\\\/rigiconurology\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@Rigicon\\\/podcasts\",\"https:\\\/\\\/www.youtube.com\\\/Rigicon\",\"https:\\\/\\\/www.threads.net\\\/@rigiconurology\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rigicon\\\/\"],\"description\":\"Rigicon is a global provider of innovative, diverse, and complete portfolio of prosthetic urology options.\",\"email\":\"operations@rigicon.com\",\"telephone\":\"+1 (888) 202-9790\",\"legalName\":\"Rigicon, Inc.\",\"vatID\":\"81-3545645\",\"taxID\":\"81-3545645\",\"duns\":\"045247683\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Corpus Spongiosum (Harnr\u00f6hrenschwellk\u00f6rper)","description":"Erfahren Sie mehr \u00fcber das Corpus Spongiosum, das die Harnr\u00f6hre umgebende erektile Gewebe, seine Rolle bei Erektionen und seine klinische Bedeutung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rigicon.com\/de\/glossary-term\/corpus-spongiosum-harnrohrenschwellkorper\/","og_locale":"de_DE","og_type":"article","og_title":"Corpus Spongiosum (Harnr\u00f6hrenschwellk\u00f6rper): Anatomy, Function, and Klinische Bedeutung","og_description":"Erfahren Sie mehr \u00fcber das Corpus Spongiosum, ein wichtiges erektiles Gewebe im Penis, das die Harnr\u00f6hre umgibt, seine Rolle bei der Erektion und seine klinische Bedeutung.","og_url":"https:\/\/www.rigicon.com\/de\/glossary-term\/corpus-spongiosum-harnrohrenschwellkorper\/","og_site_name":"Rigicon","article_publisher":"https:\/\/www.facebook.com\/rigiconurology\/","og_image":[{"width":1440,"height":718,"url":"https:\/\/www.rigicon.com\/wp-content\/uploads\/2025\/05\/header-d.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_title":"Corpus Spongiosum (Harnr\u00f6hrenschwellk\u00f6rper): Anatomy, Function, and Klinische Bedeutung","twitter_description":"Erfahren Sie mehr \u00fcber das Corpus Spongiosum, ein wichtiges erektiles Gewebe im Penis, das die Harnr\u00f6hre umgibt, seine Rolle bei der Erektion und seine klinische Bedeutung.","twitter_site":"@rigiconurology","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rigicon.com\/de\/glossary-term\/corpus-spongiosum-harnrohrenschwellkorper\/","url":"https:\/\/www.rigicon.com\/de\/glossary-term\/corpus-spongiosum-harnrohrenschwellkorper\/","name":"Corpus Spongiosum (Harnr\u00f6hrenschwellk\u00f6rper)","isPartOf":{"@id":"https:\/\/www.rigicon.com\/de\/#website"},"datePublished":"2025-06-12T08:09:33+00:00","description":"Erfahren Sie mehr \u00fcber das Corpus Spongiosum, das die Harnr\u00f6hre umgebende erektile Gewebe, seine Rolle bei Erektionen und seine klinische Bedeutung.","breadcrumb":{"@id":"https:\/\/www.rigicon.com\/de\/glossary-term\/corpus-spongiosum-harnrohrenschwellkorper\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rigicon.com\/de\/glossary-term\/corpus-spongiosum-harnrohrenschwellkorper\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rigicon.com\/de\/glossary-term\/corpus-spongiosum-harnrohrenschwellkorper\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.rigicon.com\/de\/"},{"@type":"ListItem","position":2,"name":"Glossary Terms","item":"https:\/\/www.rigicon.com\/de\/urology-glossary\/"},{"@type":"ListItem","position":3,"name":"Corpus Spongiosum (Harnr\u00f6hrenschwellk\u00f6rper)"}]},{"@type":"WebSite","@id":"https:\/\/www.rigicon.com\/de\/#website","url":"https:\/\/www.rigicon.com\/de\/","name":"Rigicon","description":"Innovative Urological Solutions","publisher":{"@id":"https:\/\/www.rigicon.com\/de\/#organization"},"alternateName":"Innovative Urological Solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rigicon.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.rigicon.com\/de\/#organization","name":"Rigicon, Inc.","alternateName":"Innovative Urological Solutions","url":"https:\/\/www.rigicon.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.rigicon.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.rigicon.com\/wp-content\/uploads\/2024\/07\/cropped-Logo-Square-Kopya.jpg","contentUrl":"https:\/\/www.rigicon.com\/wp-content\/uploads\/2024\/07\/cropped-Logo-Square-Kopya.jpg","width":512,"height":512,"caption":"Rigicon, Inc."},"image":{"@id":"https:\/\/www.rigicon.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rigiconurology\/","https:\/\/x.com\/rigiconurology","https:\/\/www.instagram.com\/rigiconurology\/","https:\/\/www.youtube.com\/@Rigicon\/podcasts","https:\/\/www.youtube.com\/Rigicon","https:\/\/www.threads.net\/@rigiconurology","https:\/\/www.linkedin.com\/company\/rigicon\/"],"description":"Rigicon is a global provider of innovative, diverse, and complete portfolio of prosthetic urology options.","email":"operations@rigicon.com","telephone":"+1 (888) 202-9790","legalName":"Rigicon, Inc.","vatID":"81-3545645","taxID":"81-3545645","duns":"045247683"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.rigicon.com\/de\/wp-json\/wp\/v2\/glossary-term\/11777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rigicon.com\/de\/wp-json\/wp\/v2\/glossary-term"}],"about":[{"href":"https:\/\/www.rigicon.com\/de\/wp-json\/wp\/v2\/types\/glossary-term"}],"wp:attachment":[{"href":"https:\/\/www.rigicon.com\/de\/wp-json\/wp\/v2\/media?parent=11777"}],"wp:term":[{"taxonomy":"glossary-category","embeddable":true,"href":"https:\/\/www.rigicon.com\/de\/wp-json\/wp\/v2\/glossary-category?post=11777"},{"taxonomy":"glossary-product","embeddable":true,"href":"https:\/\/www.rigicon.com\/de\/wp-json\/wp\/v2\/glossary-product?post=11777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}